﻿{"id":30799,"date":"2026-08-12T14:24:42","date_gmt":"2026-08-12T12:24:42","guid":{"rendered":"https:\/\/iiclione.esteri.it\/?page_id=30799"},"modified":"2026-08-21T13:29:00","modified_gmt":"2026-08-21T11:29:00","slug":"les-propositions-culturelles","status":"publish","type":"page","link":"https:\/\/iiclione.esteri.it\/fr\/chi-siamo\/comment-nous-contacter\/les-propositions-culturelles\/","title":{"rendered":"Propositions culturelles"},"content":{"rendered":"<p>Les propositions culturelles peuvent \u00eatre envoy\u00e9es \u00e0 l\u2019adresse <strong><a href=\"mailto:info.iiclyon@esteri.it\">info.iiclyon@esteri.it<\/a><\/strong>.<\/p>\n<p>Si une proposition retient notre attention, nous prendrons soin de vous recontacter afin d\u2019obtenir les \u00e9ventuelles informations compl\u00e9mentaires n\u00e9cessaires. Compte tenu du tr\u00e8s grand nombre de propositions que nous recevons quotidiennement, nous ne serons malheureusement en mesure de r\u00e9pondre qu\u2019aux projets susceptibles d\u2019\u00eatre pris en consid\u00e9ration dans le cadre de notre programmation.<\/p>\n<p>Les propositions envoy\u00e9es \u00e0 d\u2019autres adresses \u00e9lectroniques, par courrier postal, pr\u00e9sent\u00e9es par t\u00e9l\u00e9phone ou en personne ne seront pas examin\u00e9es.<\/p>\n<p>Merci de votre compr\u00e9hension.<\/p>\n<p>***<\/p>\n<p>Pour en savoir plus sur les politiques de traitement des donn\u00e9es \u00e0 caract\u00e8re personnel relatives aux propositions soumises, cliquez <a class=\"decorated-link\" href=\"https:\/\/iiclione.esteri.it\/fr\/amministrazione-trasparente\/politique-de-traitement-des-donnees-a-caractere-personnel\/\" rel=\"noopener\" data-start=\"132\" data-end=\"237\">ici<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"Les propositions culturelles peuvent \u00eatre envoy\u00e9es \u00e0 l\u2019adresse info.iiclyon@esteri.it. Si une proposition retient notre attention, nous prendrons soin de vous recontacter afin d\u2019obtenir les \u00e9ventuelles informations compl\u00e9mentaires n\u00e9cessaires. Compte tenu du tr\u00e8s grand nombre de propositions que nous recevons quotidiennement, nous ne serons malheureusement en mesure de r\u00e9pondre qu\u2019aux projets susceptibles d\u2019\u00eatre pris en consid\u00e9ration [&hellip;]","protected":false},"author":5,"featured_media":0,"parent":132,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-30799","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/iiclione.esteri.it\/fr\/wp-json\/wp\/v2\/pages\/30799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iiclione.esteri.it\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iiclione.esteri.it\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iiclione.esteri.it\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/iiclione.esteri.it\/fr\/wp-json\/wp\/v2\/comments?post=30799"}],"version-history":[{"count":3,"href":"https:\/\/iiclione.esteri.it\/fr\/wp-json\/wp\/v2\/pages\/30799\/revisions"}],"predecessor-version":[{"id":31060,"href":"https:\/\/iiclione.esteri.it\/fr\/wp-json\/wp\/v2\/pages\/30799\/revisions\/31060"}],"up":[{"embeddable":true,"href":"https:\/\/iiclione.esteri.it\/fr\/wp-json\/wp\/v2\/pages\/132"}],"wp:attachment":[{"href":"https:\/\/iiclione.esteri.it\/fr\/wp-json\/wp\/v2\/media?parent=30799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}